{"id":3774,"date":"2026-07-11T09:03:00","date_gmt":"2026-07-11T09:03:00","guid":{"rendered":"https:\/\/metamorphosis-project.org\/?p=3774"},"modified":"2026-07-21T03:31:12","modified_gmt":"2026-07-21T03:31:12","slug":"deux-jours-de-tomodensitometrie-sur-des-salamandres-europeennes-et-asiatiques-issues-de-la-collection-specola-a-dijon","status":"publish","type":"post","link":"https:\/\/metamorphosis-project.org\/fr\/nouvelles\/deux-jours-de-tomodensitometrie-sur-des-salamandres-europeennes-et-asiatiques-issues-de-la-collection-specola-a-dijon\/","title":{"rendered":"Deux jours consacr\u00e9s \u00e0 la tomodensitom\u00e9trie des salamandres europ\u00e9ennes et asiatiques de la collection de la Specola \u00e0 Dijon !"},"content":{"rendered":"<div class=\"wp-block-jetpack-slideshow aligncenter\" data-effect=\"slide\" style=\"--aspect-ratio:calc(1024 \/ 769)\"><div class=\"wp-block-jetpack-slideshow_container swiper\"><ul class=\"wp-block-jetpack-slideshow_swiper-wrapper swiper-wrapper\"><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"769\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-3781\" data-id=\"3781\" data-aspect-ratio=\"1024 \/ 769\" src=\"https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/07\/PXL_20260708_131910309-2-1024x769.jpg\" srcset=\"https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/07\/PXL_20260708_131910309-2-1024x769.jpg 1024w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/07\/PXL_20260708_131910309-2-300x225.jpg 300w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/07\/PXL_20260708_131910309-2-768x577.jpg 768w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/07\/PXL_20260708_131910309-2-1536x1153.jpg 1536w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/07\/PXL_20260708_131910309-2-2048x1538.jpg 2048w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/07\/PXL_20260708_131910309-2-16x12.jpg 16w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"769\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-3776\" data-id=\"3776\" data-aspect-ratio=\"1024 \/ 769\" src=\"https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/07\/PXL_20260708_131742697-1024x769.jpg\" srcset=\"https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/07\/PXL_20260708_131742697-1024x769.jpg 1024w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/07\/PXL_20260708_131742697-300x225.jpg 300w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/07\/PXL_20260708_131742697-768x577.jpg 768w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/07\/PXL_20260708_131742697-1536x1153.jpg 1536w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/07\/PXL_20260708_131742697-2048x1538.jpg 2048w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/07\/PXL_20260708_131742697-16x12.jpg 16w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"769\" height=\"1024\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-3782\" data-id=\"3782\" data-aspect-ratio=\"769 \/ 1024\" src=\"https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/07\/PXL_20260708_131710500.MP2_-769x1024.jpg\" srcset=\"https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/07\/PXL_20260708_131710500.MP2_-769x1024.jpg 769w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/07\/PXL_20260708_131710500.MP2_-225x300.jpg 225w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/07\/PXL_20260708_131710500.MP2_-768x1023.jpg 768w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/07\/PXL_20260708_131710500.MP2_-1153x1536.jpg 1153w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/07\/PXL_20260708_131710500.MP2_-1538x2048.jpg 1538w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/07\/PXL_20260708_131710500.MP2_-9x12.jpg 9w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/07\/PXL_20260708_131710500.MP2_-scaled.jpg 1922w\" sizes=\"(max-width: 769px) 100vw, 769px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"769\" height=\"1024\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-3779\" data-id=\"3779\" data-aspect-ratio=\"769 \/ 1024\" src=\"https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/07\/PXL_20260708_131633794-769x1024.jpg\" srcset=\"https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/07\/PXL_20260708_131633794-769x1024.jpg 769w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/07\/PXL_20260708_131633794-225x300.jpg 225w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/07\/PXL_20260708_131633794-768x1023.jpg 768w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/07\/PXL_20260708_131633794-1153x1536.jpg 1153w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/07\/PXL_20260708_131633794-1538x2048.jpg 1538w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/07\/PXL_20260708_131633794-9x12.jpg 9w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/07\/PXL_20260708_131633794-scaled.jpg 1922w\" sizes=\"(max-width: 769px) 100vw, 769px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"769\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-3778\" data-id=\"3778\" data-aspect-ratio=\"1024 \/ 769\" src=\"https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/07\/PXL_20260709_072801062.MP_-1024x769.jpg\" srcset=\"https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/07\/PXL_20260709_072801062.MP_-1024x769.jpg 1024w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/07\/PXL_20260709_072801062.MP_-300x225.jpg 300w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/07\/PXL_20260709_072801062.MP_-768x577.jpg 768w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/07\/PXL_20260709_072801062.MP_-1536x1153.jpg 1536w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/07\/PXL_20260709_072801062.MP_-2048x1538.jpg 2048w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/07\/PXL_20260709_072801062.MP_-16x12.jpg 16w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"769\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-3777\" data-id=\"3777\" data-aspect-ratio=\"1024 \/ 769\" src=\"https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/07\/PXL_20250129_1519241281-1024x769.jpg\" srcset=\"https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/07\/PXL_20250129_1519241281-1024x769.jpg 1024w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/07\/PXL_20250129_1519241281-300x225.jpg 300w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/07\/PXL_20250129_1519241281-768x577.jpg 768w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/07\/PXL_20250129_1519241281-1536x1153.jpg 1536w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/07\/PXL_20250129_1519241281-2048x1538.jpg 2048w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/07\/PXL_20250129_1519241281-16x12.jpg 16w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><\/ul><a class=\"wp-block-jetpack-slideshow_button-prev swiper-button-prev swiper-button-white\" role=\"button\"><\/a><a class=\"wp-block-jetpack-slideshow_button-next swiper-button-next swiper-button-white\" role=\"button\"><\/a><a aria-label=\"Pause du diaporama\" class=\"wp-block-jetpack-slideshow_button-pause\" role=\"button\"><\/a><div class=\"wp-block-jetpack-slideshow_pagination swiper-pagination swiper-pagination-white\"><\/div><\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Ces deux derniers jours, j\u2019\u00e9tais \u00e0 Dijon pour r\u00e9aliser des tomodensitom\u00e9tries sur des salamandres europ\u00e9ennes et asiatiques issues de la collection de la Specola, avec l\u2019aide pr\u00e9cieuse de Lauriane Poloni \u00e0 la plateforme d\u2019imagerie GISMO du laboratoire de biog\u00e9osciences de l\u2019Universit\u00e9 de Bourgogne. Ces sp\u00e9cimens r\u00e9cemment scann\u00e9s viendront enrichir notre ensemble de donn\u00e9es macro\u00e9volutives, ce qui nous permettra d\u2019\u00e9tudier comment les variations dans le cycle de vie et les trajectoires de d\u00e9veloppement (ontog\u00e9n\u00e9tiques) ont fa\u00e7onn\u00e9 l\u2019\u00e9volution de la t\u00eate des salamandres. En int\u00e9grant ces esp\u00e8ces suppl\u00e9mentaires, nous esp\u00e9rons mieux comprendre les liens entre le d\u00e9veloppement, la diversit\u00e9 des cycles de vie et l\u2019\u00e9volution morphologique chez les salamandres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vient maintenant l'\u00e9tape suivante : segmenter ces sp\u00e9cimens nouvellement num\u00e9ris\u00e9s et y placer des rep\u00e8res avant de les ajouter \u00e0 notre base de donn\u00e9es qui ne cesse de s'enrichir. C'est un processus qui prend du temps, mais chaque nouveau sp\u00e9cimen nous rapproche un peu plus de la r\u00e9ponse \u00e0 nos questions sur l'\u00e9volution. Nous esp\u00e9rons pouvoir bient\u00f4t vous faire part de nouveaux r\u00e9sultats passionnants ! <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Restez \u00e0 l'\u00e9coute !<\/p>","protected":false},"excerpt":{"rendered":"<p>Ces deux derniers jours, j'\u00e9tais \u00e0 Dijon pour r\u00e9aliser des tomodensitom\u00e9tries sur des salamandres europ\u00e9ennes et asiatiques issues de la collection de la Specola, avec l'aide pr\u00e9cieuse de Lauriane Poloni \u00e0 la plateforme d'imagerie GISMO du laboratoire de biog\u00e9osciences de l'Universit\u00e9 de Bourgogne. Ces sp\u00e9cimens r\u00e9cemment num\u00e9ris\u00e9s vont\u2026<\/p>","protected":false},"author":2,"featured_media":3781,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[29],"tags":[],"class_list":["post-3774","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Over the past two days, I was in Dijon CT-scanning European and Asian salamanders from the Specola collection with the invaluable help of Lauriane Poloni at the GISMO imaging platform, University of Bourgogne\u2019s Biogeosciences laboratory. These newly scanned specimens will\u2026\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Anne-Claire Fabre\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/metamorphosis-project.org\/fr\/nouvelles\/deux-jours-de-tomodensitometrie-sur-des-salamandres-europeennes-et-asiatiques-issues-de-la-collection-specola-a-dijon\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Meta-Morphosis Project - How life cycle variation drives biodiversity in changing environments\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Two days of CT scanning European and Asian salamanders from the Specola collection in Dijon! - Meta-Morphosis Project\" \/>\n\t\t<meta property=\"og:description\" content=\"Over the past two days, I was in Dijon CT-scanning European and Asian salamanders from the Specola collection with the invaluable help of Lauriane Poloni at the GISMO imaging platform, University of Bourgogne\u2019s Biogeosciences laboratory. These newly scanned specimens will\u2026\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/metamorphosis-project.org\/fr\/nouvelles\/deux-jours-de-tomodensitometrie-sur-des-salamandres-europeennes-et-asiatiques-issues-de-la-collection-specola-a-dijon\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-07-11T09:03:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-07-21T03:31:12+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@kafka_project\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Two days of CT scanning European and Asian salamanders from the Specola collection in Dijon! - Meta-Morphosis Project\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Over the past two days, I was in Dijon CT-scanning European and Asian salamanders from the Specola collection with the invaluable help of Lauriane Poloni at the GISMO imaging platform, University of Bourgogne\u2019s Biogeosciences laboratory. These newly scanned specimens will\u2026\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@kafka_project\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr\\\/nouvelles\\\/deux-jours-de-tomodensitometrie-sur-des-salamandres-europeennes-et-asiatiques-issues-de-la-collection-specola-a-dijon\\\/#blogposting\",\"name\":\"Two days of CT scanning European and Asian salamanders from the Specola collection in Dijon! - Meta-Morphosis Project\",\"headline\":\"Two days of CT scanning European and Asian salamanders from the Specola collection in Dijon!\",\"author\":{\"@id\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr\\\/author\\\/acfabre\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/metamorphosis-project.org\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/PXL_20260708_131910309-2-scaled.jpg\",\"width\":2560,\"height\":1922},\"datePublished\":\"2026-07-11T09:03:00+00:00\",\"dateModified\":\"2026-07-21T03:31:12+00:00\",\"inLanguage\":\"fr-FR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr\\\/nouvelles\\\/deux-jours-de-tomodensitometrie-sur-des-salamandres-europeennes-et-asiatiques-issues-de-la-collection-specola-a-dijon\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr\\\/nouvelles\\\/deux-jours-de-tomodensitometrie-sur-des-salamandres-europeennes-et-asiatiques-issues-de-la-collection-specola-a-dijon\\\/#webpage\"},\"articleSection\":\"News\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr\\\/nouvelles\\\/deux-jours-de-tomodensitometrie-sur-des-salamandres-europeennes-et-asiatiques-issues-de-la-collection-specola-a-dijon\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr\\\/categorie\\\/nouvelles\\\/#listItem\",\"name\":\"News\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr\\\/categorie\\\/nouvelles\\\/#listItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr\\\/categorie\\\/nouvelles\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr\\\/nouvelles\\\/deux-jours-de-tomodensitometrie-sur-des-salamandres-europeennes-et-asiatiques-issues-de-la-collection-specola-a-dijon\\\/#listItem\",\"name\":\"Two days of CT scanning European and Asian salamanders from the Specola collection in Dijon!\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr\\\/nouvelles\\\/deux-jours-de-tomodensitometrie-sur-des-salamandres-europeennes-et-asiatiques-issues-de-la-collection-specola-a-dijon\\\/#listItem\",\"position\":3,\"name\":\"Two days of CT scanning European and Asian salamanders from the Specola collection in Dijon!\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr\\\/categorie\\\/nouvelles\\\/#listItem\",\"name\":\"News\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr\\\/#organization\",\"name\":\"Meta-Morphosis Project\",\"description\":\"How life cycle variation drives biodiversity in changing environments\",\"url\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":{\"__changed\":[\"mobile\"]},\"@id\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr\\\/nouvelles\\\/deux-jours-de-tomodensitometrie-sur-des-salamandres-europeennes-et-asiatiques-issues-de-la-collection-specola-a-dijon\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr\\\/nouvelles\\\/deux-jours-de-tomodensitometrie-sur-des-salamandres-europeennes-et-asiatiques-issues-de-la-collection-specola-a-dijon\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/twitter.com\\\/kafka_project\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCIjYQlwQGZqxnm3GAFkt6_A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr\\\/author\\\/acfabre\\\/#author\",\"url\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr\\\/author\\\/acfabre\\\/\",\"name\":\"Anne-Claire Fabre\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr\\\/nouvelles\\\/deux-jours-de-tomodensitometrie-sur-des-salamandres-europeennes-et-asiatiques-issues-de-la-collection-specola-a-dijon\\\/#webpage\",\"url\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr\\\/nouvelles\\\/deux-jours-de-tomodensitometrie-sur-des-salamandres-europeennes-et-asiatiques-issues-de-la-collection-specola-a-dijon\\\/\",\"name\":\"Two days of CT scanning European and Asian salamanders from the Specola collection in Dijon! - Meta-Morphosis Project\",\"description\":\"Over the past two days, I was in Dijon CT-scanning European and Asian salamanders from the Specola collection with the invaluable help of Lauriane Poloni at the GISMO imaging platform, University of Bourgogne\\u2019s Biogeosciences laboratory. These newly scanned specimens will\\u2026\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr\\\/nouvelles\\\/deux-jours-de-tomodensitometrie-sur-des-salamandres-europeennes-et-asiatiques-issues-de-la-collection-specola-a-dijon\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr\\\/author\\\/acfabre\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr\\\/author\\\/acfabre\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/metamorphosis-project.org\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/PXL_20260708_131910309-2-scaled.jpg\",\"@id\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr\\\/nouvelles\\\/deux-jours-de-tomodensitometrie-sur-des-salamandres-europeennes-et-asiatiques-issues-de-la-collection-specola-a-dijon\\\/#mainImage\",\"width\":2560,\"height\":1922},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr\\\/nouvelles\\\/deux-jours-de-tomodensitometrie-sur-des-salamandres-europeennes-et-asiatiques-issues-de-la-collection-specola-a-dijon\\\/#mainImage\"},\"datePublished\":\"2026-07-11T09:03:00+00:00\",\"dateModified\":\"2026-07-21T03:31:12+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr\\\/\",\"name\":\"Meta-Morphosis Project\",\"description\":\"How life cycle variation drives biodiversity in changing environments\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Deux jours consacr\u00e9s \u00e0 la tomodensitom\u00e9trie des salamandres europ\u00e9ennes et asiatiques de la collection de la Specola \u00e0 Dijon ! - Projet Meta-Morphosis","description":"Ces deux derniers jours, j'\u00e9tais \u00e0 Dijon pour r\u00e9aliser des tomodensitom\u00e9tries sur des salamandres europ\u00e9ennes et asiatiques issues de la collection de la Specola, avec l'aide pr\u00e9cieuse de Lauriane Poloni \u00e0 la plateforme d'imagerie GISMO du laboratoire de biog\u00e9osciences de l'Universit\u00e9 de Bourgogne. Ces sp\u00e9cimens r\u00e9cemment num\u00e9ris\u00e9s vont\u2026","canonical_url":"https:\/\/metamorphosis-project.org\/fr\/nouvelles\/deux-jours-de-tomodensitometrie-sur-des-salamandres-europeennes-et-asiatiques-issues-de-la-collection-specola-a-dijon\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/metamorphosis-project.org\/fr\/nouvelles\/deux-jours-de-tomodensitometrie-sur-des-salamandres-europeennes-et-asiatiques-issues-de-la-collection-specola-a-dijon\/#blogposting","name":"Two days of CT scanning European and Asian salamanders from the Specola collection in Dijon! - Meta-Morphosis Project","headline":"Two days of CT scanning European and Asian salamanders from the Specola collection in Dijon!","author":{"@id":"https:\/\/metamorphosis-project.org\/fr\/author\/acfabre\/#author"},"publisher":{"@id":"https:\/\/metamorphosis-project.org\/fr\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/07\/PXL_20260708_131910309-2-scaled.jpg","width":2560,"height":1922},"datePublished":"2026-07-11T09:03:00+00:00","dateModified":"2026-07-21T03:31:12+00:00","inLanguage":"fr-FR","mainEntityOfPage":{"@id":"https:\/\/metamorphosis-project.org\/fr\/nouvelles\/deux-jours-de-tomodensitometrie-sur-des-salamandres-europeennes-et-asiatiques-issues-de-la-collection-specola-a-dijon\/#webpage"},"isPartOf":{"@id":"https:\/\/metamorphosis-project.org\/fr\/nouvelles\/deux-jours-de-tomodensitometrie-sur-des-salamandres-europeennes-et-asiatiques-issues-de-la-collection-specola-a-dijon\/#webpage"},"articleSection":"News"},{"@type":"BreadcrumbList","@id":"https:\/\/metamorphosis-project.org\/fr\/nouvelles\/deux-jours-de-tomodensitometrie-sur-des-salamandres-europeennes-et-asiatiques-issues-de-la-collection-specola-a-dijon\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/metamorphosis-project.org\/fr#listItem","position":1,"name":"Home","item":"https:\/\/metamorphosis-project.org\/fr","nextItem":{"@type":"ListItem","@id":"https:\/\/metamorphosis-project.org\/fr\/categorie\/nouvelles\/#listItem","name":"News"}},{"@type":"ListItem","@id":"https:\/\/metamorphosis-project.org\/fr\/categorie\/nouvelles\/#listItem","position":2,"name":"News","item":"https:\/\/metamorphosis-project.org\/fr\/categorie\/nouvelles\/","nextItem":{"@type":"ListItem","@id":"https:\/\/metamorphosis-project.org\/fr\/nouvelles\/deux-jours-de-tomodensitometrie-sur-des-salamandres-europeennes-et-asiatiques-issues-de-la-collection-specola-a-dijon\/#listItem","name":"Two days of CT scanning European and Asian salamanders from the Specola collection in Dijon!"},"previousItem":{"@type":"ListItem","@id":"https:\/\/metamorphosis-project.org\/fr#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/metamorphosis-project.org\/fr\/nouvelles\/deux-jours-de-tomodensitometrie-sur-des-salamandres-europeennes-et-asiatiques-issues-de-la-collection-specola-a-dijon\/#listItem","position":3,"name":"Two days of CT scanning European and Asian salamanders from the Specola collection in Dijon!","previousItem":{"@type":"ListItem","@id":"https:\/\/metamorphosis-project.org\/fr\/categorie\/nouvelles\/#listItem","name":"News"}}]},{"@type":"Organization","@id":"https:\/\/metamorphosis-project.org\/fr\/#organization","name":"Meta-Morphosis Project","description":"How life cycle variation drives biodiversity in changing environments","url":"https:\/\/metamorphosis-project.org\/fr\/","logo":{"@type":"ImageObject","url":{"__changed":["mobile"]},"@id":"https:\/\/metamorphosis-project.org\/fr\/nouvelles\/deux-jours-de-tomodensitometrie-sur-des-salamandres-europeennes-et-asiatiques-issues-de-la-collection-specola-a-dijon\/#organizationLogo"},"image":{"@id":"https:\/\/metamorphosis-project.org\/fr\/nouvelles\/deux-jours-de-tomodensitometrie-sur-des-salamandres-europeennes-et-asiatiques-issues-de-la-collection-specola-a-dijon\/#organizationLogo"},"sameAs":["https:\/\/twitter.com\/kafka_project","https:\/\/www.youtube.com\/channel\/UCIjYQlwQGZqxnm3GAFkt6_A"]},{"@type":"Person","@id":"https:\/\/metamorphosis-project.org\/fr\/author\/acfabre\/#author","url":"https:\/\/metamorphosis-project.org\/fr\/author\/acfabre\/","name":"Anne-Claire Fabre"},{"@type":"WebPage","@id":"https:\/\/metamorphosis-project.org\/fr\/nouvelles\/deux-jours-de-tomodensitometrie-sur-des-salamandres-europeennes-et-asiatiques-issues-de-la-collection-specola-a-dijon\/#webpage","url":"https:\/\/metamorphosis-project.org\/fr\/nouvelles\/deux-jours-de-tomodensitometrie-sur-des-salamandres-europeennes-et-asiatiques-issues-de-la-collection-specola-a-dijon\/","name":"Two days of CT scanning European and Asian salamanders from the Specola collection in Dijon! - Meta-Morphosis Project","description":"Over the past two days, I was in Dijon CT-scanning European and Asian salamanders from the Specola collection with the invaluable help of Lauriane Poloni at the GISMO imaging platform, University of Bourgogne\u2019s Biogeosciences laboratory. These newly scanned specimens will\u2026","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/metamorphosis-project.org\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/metamorphosis-project.org\/fr\/nouvelles\/deux-jours-de-tomodensitometrie-sur-des-salamandres-europeennes-et-asiatiques-issues-de-la-collection-specola-a-dijon\/#breadcrumblist"},"author":{"@id":"https:\/\/metamorphosis-project.org\/fr\/author\/acfabre\/#author"},"creator":{"@id":"https:\/\/metamorphosis-project.org\/fr\/author\/acfabre\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/07\/PXL_20260708_131910309-2-scaled.jpg","@id":"https:\/\/metamorphosis-project.org\/fr\/nouvelles\/deux-jours-de-tomodensitometrie-sur-des-salamandres-europeennes-et-asiatiques-issues-de-la-collection-specola-a-dijon\/#mainImage","width":2560,"height":1922},"primaryImageOfPage":{"@id":"https:\/\/metamorphosis-project.org\/fr\/nouvelles\/deux-jours-de-tomodensitometrie-sur-des-salamandres-europeennes-et-asiatiques-issues-de-la-collection-specola-a-dijon\/#mainImage"},"datePublished":"2026-07-11T09:03:00+00:00","dateModified":"2026-07-21T03:31:12+00:00"},{"@type":"WebSite","@id":"https:\/\/metamorphosis-project.org\/fr\/#website","url":"https:\/\/metamorphosis-project.org\/fr\/","name":"Meta-Morphosis Project","description":"How life cycle variation drives biodiversity in changing environments","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/metamorphosis-project.org\/fr\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"Meta-Morphosis Project - How life cycle variation drives biodiversity in changing environments","og:type":"article","og:title":"Two days of CT scanning European and Asian salamanders from the Specola collection in Dijon! - Meta-Morphosis Project","og:description":"Over the past two days, I was in Dijon CT-scanning European and Asian salamanders from the Specola collection with the invaluable help of Lauriane Poloni at the GISMO imaging platform, University of Bourgogne\u2019s Biogeosciences laboratory. These newly scanned specimens will\u2026","og:url":"https:\/\/metamorphosis-project.org\/fr\/nouvelles\/deux-jours-de-tomodensitometrie-sur-des-salamandres-europeennes-et-asiatiques-issues-de-la-collection-specola-a-dijon\/","article:published_time":"2026-07-11T09:03:00+00:00","article:modified_time":"2026-07-21T03:31:12+00:00","twitter:card":"summary_large_image","twitter:site":"@kafka_project","twitter:title":"Two days of CT scanning European and Asian salamanders from the Specola collection in Dijon! - Meta-Morphosis Project","twitter:description":"Over the past two days, I was in Dijon CT-scanning European and Asian salamanders from the Specola collection with the invaluable help of Lauriane Poloni at the GISMO imaging platform, University of Bourgogne\u2019s Biogeosciences laboratory. These newly scanned specimens will\u2026","twitter:creator":"@kafka_project"},"aioseo_meta_data":{"post_id":"3774","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"schemas":[],"titles":[],"descriptions":[],"socialPosts":{"email":{"subject":"","preview":"","content":""},"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2026-07-20 09:19:13","updated":"2026-07-21 04:15:57","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/metamorphosis-project.org\/fr\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/metamorphosis-project.org\/fr\/categorie\/nouvelles\/\" title=\"News\">News<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tTwo days of CT scanning European and Asian salamanders from the Specola collection in Dijon!\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/metamorphosis-project.org\/fr"},{"label":"News","link":"https:\/\/metamorphosis-project.org\/fr\/categorie\/nouvelles\/"},{"label":"Two days of CT scanning European and Asian salamanders from the Specola collection in Dijon!","link":"https:\/\/metamorphosis-project.org\/fr\/nouvelles\/deux-jours-de-tomodensitometrie-sur-des-salamandres-europeennes-et-asiatiques-issues-de-la-collection-specola-a-dijon\/"}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/07\/PXL_20260708_131910309-2-scaled.jpg","_links":{"self":[{"href":"https:\/\/metamorphosis-project.org\/fr\/wp-json\/wp\/v2\/posts\/3774","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/metamorphosis-project.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/metamorphosis-project.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/metamorphosis-project.org\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/metamorphosis-project.org\/fr\/wp-json\/wp\/v2\/comments?post=3774"}],"version-history":[{"count":2,"href":"https:\/\/metamorphosis-project.org\/fr\/wp-json\/wp\/v2\/posts\/3774\/revisions"}],"predecessor-version":[{"id":3787,"href":"https:\/\/metamorphosis-project.org\/fr\/wp-json\/wp\/v2\/posts\/3774\/revisions\/3787"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/metamorphosis-project.org\/fr\/wp-json\/wp\/v2\/media\/3781"}],"wp:attachment":[{"href":"https:\/\/metamorphosis-project.org\/fr\/wp-json\/wp\/v2\/media?parent=3774"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/metamorphosis-project.org\/fr\/wp-json\/wp\/v2\/categories?post=3774"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/metamorphosis-project.org\/fr\/wp-json\/wp\/v2\/tags?post=3774"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}