{"id":3660,"date":"2025-08-30T15:12:00","date_gmt":"2025-08-30T15:12:00","guid":{"rendered":"https:\/\/metamorphosis-project.org\/?p=3660"},"modified":"2026-07-01T20:12:49","modified_gmt":"2026-07-01T20:12:49","slug":"conference-eseb-a-barcelone-ole","status":"publish","type":"post","link":"https:\/\/metamorphosis-project.org\/fr\/nouvelles\/conference-eseb-a-barcelone-ole\/","title":{"rendered":"Conf\u00e9rence de l'ESEB \u00e0 Barcelone ! Ol\u00e9 !"},"content":{"rendered":"<div class=\"wp-block-jetpack-slideshow aligncenter\" data-effect=\"slide\" style=\"--aspect-ratio:calc(1200 \/ 1200)\"><div class=\"wp-block-jetpack-slideshow_container swiper\"><ul class=\"wp-block-jetpack-slideshow_swiper-wrapper swiper-wrapper\"><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1200\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-3683\" data-id=\"3683\" data-aspect-ratio=\"1200 \/ 1200\" src=\"https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/1000046350.jpg\" srcset=\"https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/1000046350.jpg 1200w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/1000046350-300x300.jpg 300w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/1000046350-1024x1024.jpg 1024w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/1000046350-150x150.jpg 150w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/1000046350-768x768.jpg 768w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/1000046350-12x12.jpg 12w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/1000046350-24x24.jpg 24w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/1000046350-48x48.jpg 48w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/1000046350-96x96.jpg 96w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1500\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-3684\" data-id=\"3684\" data-aspect-ratio=\"2000 \/ 1500\" src=\"https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/1000046349.jpg\" srcset=\"https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/1000046349.jpg 2000w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/1000046349-300x225.jpg 300w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/1000046349-1024x768.jpg 1024w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/1000046349-768x576.jpg 768w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/1000046349-1536x1152.jpg 1536w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/1000046349-16x12.jpg 16w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1922\" height=\"2560\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-3680\" data-id=\"3680\" data-aspect-ratio=\"1922 \/ 2560\" src=\"https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/PXL_20250821_092108567-2-scaled.jpg\" srcset=\"https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/PXL_20250821_092108567-2-scaled.jpg 1922w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/PXL_20250821_092108567-2-225x300.jpg 225w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/PXL_20250821_092108567-2-769x1024.jpg 769w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/PXL_20250821_092108567-2-768x1023.jpg 768w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/PXL_20250821_092108567-2-1153x1536.jpg 1153w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/PXL_20250821_092108567-2-1538x2048.jpg 1538w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/PXL_20250821_092108567-2-9x12.jpg 9w\" sizes=\"(max-width: 1922px) 100vw, 1922px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1922\" height=\"2560\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-3682\" data-id=\"3682\" data-aspect-ratio=\"1922 \/ 2560\" src=\"https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/PXL_20250819_1137085001-scaled.jpg\" srcset=\"https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/PXL_20250819_1137085001-scaled.jpg 1922w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/PXL_20250819_1137085001-225x300.jpg 225w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/PXL_20250819_1137085001-769x1024.jpg 769w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/PXL_20250819_1137085001-768x1023.jpg 768w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/PXL_20250819_1137085001-1153x1536.jpg 1153w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/PXL_20250819_1137085001-1538x2048.jpg 1538w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/PXL_20250819_1137085001-9x12.jpg 9w\" sizes=\"(max-width: 1922px) 100vw, 1922px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1922\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-3686\" data-id=\"3686\" data-aspect-ratio=\"2560 \/ 1922\" src=\"https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/PXL_20250818_212358207.MP1_-scaled.jpg\" srcset=\"https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/PXL_20250818_212358207.MP1_-scaled.jpg 2560w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/PXL_20250818_212358207.MP1_-300x225.jpg 300w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/PXL_20250818_212358207.MP1_-1024x769.jpg 1024w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/PXL_20250818_212358207.MP1_-768x577.jpg 768w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/PXL_20250818_212358207.MP1_-1536x1153.jpg 1536w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/PXL_20250818_212358207.MP1_-2048x1538.jpg 2048w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/PXL_20250818_212358207.MP1_-16x12.jpg 16w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1922\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-3678\" data-id=\"3678\" data-aspect-ratio=\"2560 \/ 1922\" src=\"https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/PXL_20250820_115339226-2-scaled.jpg\" srcset=\"https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/PXL_20250820_115339226-2-scaled.jpg 2560w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/PXL_20250820_115339226-2-300x225.jpg 300w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/PXL_20250820_115339226-2-1024x769.jpg 1024w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/PXL_20250820_115339226-2-768x577.jpg 768w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/PXL_20250820_115339226-2-1536x1153.jpg 1536w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/PXL_20250820_115339226-2-2048x1538.jpg 2048w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/PXL_20250820_115339226-2-16x12.jpg 16w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1922\" height=\"2560\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-3679\" data-id=\"3679\" data-aspect-ratio=\"1922 \/ 2560\" src=\"https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/PXL_20250820_120137962-2-scaled.jpg\" srcset=\"https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/PXL_20250820_120137962-2-scaled.jpg 1922w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/PXL_20250820_120137962-2-225x300.jpg 225w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/PXL_20250820_120137962-2-769x1024.jpg 769w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/PXL_20250820_120137962-2-768x1023.jpg 768w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/PXL_20250820_120137962-2-1153x1536.jpg 1153w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/PXL_20250820_120137962-2-1538x2048.jpg 1538w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/PXL_20250820_120137962-2-9x12.jpg 9w\" sizes=\"(max-width: 1922px) 100vw, 1922px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1922\" height=\"2560\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-3681\" data-id=\"3681\" data-aspect-ratio=\"1922 \/ 2560\" src=\"https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/PXL_20250820_121120781-2-scaled.jpg\" srcset=\"https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/PXL_20250820_121120781-2-scaled.jpg 1922w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/PXL_20250820_121120781-2-225x300.jpg 225w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/PXL_20250820_121120781-2-769x1024.jpg 769w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/PXL_20250820_121120781-2-768x1023.jpg 768w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/PXL_20250820_121120781-2-1153x1536.jpg 1153w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/PXL_20250820_121120781-2-1538x2048.jpg 1538w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/PXL_20250820_121120781-2-9x12.jpg 9w\" sizes=\"(max-width: 1922px) 100vw, 1922px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"751\" height=\"1000\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-3688\" data-id=\"3688\" data-aspect-ratio=\"751 \/ 1000\" src=\"https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/Sans-titre-June-30-2026-at-16.36.40-1.png\" srcset=\"https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/Sans-titre-June-30-2026-at-16.36.40-1.png 751w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/Sans-titre-June-30-2026-at-16.36.40-1-225x300.png 225w, https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/Sans-titre-June-30-2026-at-16.36.40-1-9x12.png 9w\" sizes=\"(max-width: 751px) 100vw, 751px\" \/><\/figure><\/li><\/ul><a class=\"wp-block-jetpack-slideshow_button-prev swiper-button-prev swiper-button-white\" role=\"button\"><\/a><a class=\"wp-block-jetpack-slideshow_button-next swiper-button-next swiper-button-white\" role=\"button\"><\/a><a aria-label=\"Pause du diaporama\" class=\"wp-block-jetpack-slideshow_button-pause\" role=\"button\"><\/a><div class=\"wp-block-jetpack-slideshow_pagination swiper-pagination swiper-pagination-white\"><\/div><\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Du 17 au 22 ao\u00fbt 2025, Morgane Fournier, Vivien Louppe et moi-m\u00eame avons particip\u00e9 au congr\u00e8s de la Soci\u00e9t\u00e9 europ\u00e9enne de biologie \u00e9volutive (ESEB) \u00e0 Barcelone. J\u2019ai \u00e9t\u00e9 invit\u00e9e \u00e0 intervenir dans le cadre d\u2019un symposium sur l\u2019\u00e9volution craniofaciale organis\u00e9 par Olivia Plateau et Kevin Le Verger. Cela a \u00e9t\u00e9 une formidable occasion de pr\u00e9senter le projet META-MORPHOSIS \u00e0 un large public de chercheurs issus de divers horizons de la biologie \u00e9volutive, et de participer \u00e0 des discussions stimulantes entre diff\u00e9rentes disciplines.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Par ailleurs, Vivien et Morgane ont pr\u00e9sent\u00e9 un poster mettant en avant une partie de leur projet de recherche en cours, ce qui a donn\u00e9 lieu \u00e0 de nombreux \u00e9changes int\u00e9ressants tout au long du colloque. Nous tenons \u00e0 remercier chaleureusement Olivia et Kevin pour leur invitation et pour avoir organis\u00e9 un colloque aussi inspirant. Ce fut un v\u00e9ritable plaisir de retrouver des coll\u00e8gues, d\u2019\u00e9changer des id\u00e9es avec des chercheurs issus de diff\u00e9rents domaines et de passer \u00e0 nouveau quelques jours dans la magnifique ville de Barcelone.<\/p>","protected":false},"excerpt":{"rendered":"<p>Du 17 au 22 ao\u00fbt 2025, Morgane Fournier, Vivien Louppe et moi-m\u00eame avons assist\u00e9 au congr\u00e8s de la Soci\u00e9t\u00e9 europ\u00e9enne de biologie \u00e9volutive (ESEB) \u00e0 Barcelone. J\u2019ai \u00e9t\u00e9 invit\u00e9 \u00e0 pr\u00e9senter un expos\u00e9 dans le cadre d\u2019un colloque sur l\u2019\u00e9volution craniofaciale organis\u00e9 par\u2026<\/p>","protected":false},"author":2,"featured_media":3683,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[29],"tags":[8,7,15],"class_list":["post-3660","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-biodiversity","tag-form-function","tag-morphometrics"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"From August 17 to 22, 2025, Morgane Fournier, Vivien Louppe, and I attended the European Society for Evolutionary Biology (ESEB) Congress in Barcelona. I was invited to give a talk as part of a symposium on craniofacial evolution organized by\u2026\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Anne-Claire Fabre\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/metamorphosis-project.org\/fr\/nouvelles\/conference-eseb-a-barcelone-ole\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Meta-Morphosis Project - How life cycle variation drives biodiversity in changing environments\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"ESEB conference in Barcelona! Ol\u00e9! - Meta-Morphosis Project\" \/>\n\t\t<meta property=\"og:description\" content=\"From August 17 to 22, 2025, Morgane Fournier, Vivien Louppe, and I attended the European Society for Evolutionary Biology (ESEB) Congress in Barcelona. I was invited to give a talk as part of a symposium on craniofacial evolution organized by\u2026\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/metamorphosis-project.org\/fr\/nouvelles\/conference-eseb-a-barcelone-ole\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-08-30T15:12:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-07-01T20:12:49+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@kafka_project\" \/>\n\t\t<meta name=\"twitter:title\" content=\"ESEB conference in Barcelona! Ol\u00e9! - Meta-Morphosis Project\" \/>\n\t\t<meta name=\"twitter:description\" content=\"From August 17 to 22, 2025, Morgane Fournier, Vivien Louppe, and I attended the European Society for Evolutionary Biology (ESEB) Congress in Barcelona. I was invited to give a talk as part of a symposium on craniofacial evolution organized by\u2026\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@kafka_project\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr\\\/nouvelles\\\/conference-eseb-a-barcelone-ole\\\/#blogposting\",\"name\":\"ESEB conference in Barcelona! Ol\\u00e9! - Meta-Morphosis Project\",\"headline\":\"ESEB conference in Barcelona! Ol\\u00e9!\",\"author\":{\"@id\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr\\\/author\\\/acfabre\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/metamorphosis-project.org\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/1000046350.jpg\",\"width\":1200,\"height\":1200},\"datePublished\":\"2025-08-30T15:12:00+00:00\",\"dateModified\":\"2026-07-01T20:12:49+00:00\",\"inLanguage\":\"fr-FR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr\\\/nouvelles\\\/conference-eseb-a-barcelone-ole\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr\\\/nouvelles\\\/conference-eseb-a-barcelone-ole\\\/#webpage\"},\"articleSection\":\"News, Biodiversity, Form-Function, Morphometrics\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr\\\/nouvelles\\\/conference-eseb-a-barcelone-ole\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr\\\/categorie\\\/nouvelles\\\/#listItem\",\"name\":\"News\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr\\\/categorie\\\/nouvelles\\\/#listItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr\\\/categorie\\\/nouvelles\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr\\\/nouvelles\\\/conference-eseb-a-barcelone-ole\\\/#listItem\",\"name\":\"ESEB conference in Barcelona! Ol\\u00e9!\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr\\\/nouvelles\\\/conference-eseb-a-barcelone-ole\\\/#listItem\",\"position\":3,\"name\":\"ESEB conference in Barcelona! Ol\\u00e9!\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr\\\/categorie\\\/nouvelles\\\/#listItem\",\"name\":\"News\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr\\\/#organization\",\"name\":\"Meta-Morphosis Project\",\"description\":\"How life cycle variation drives biodiversity in changing environments\",\"url\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":{\"__changed\":[\"mobile\"]},\"@id\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr\\\/nouvelles\\\/conference-eseb-a-barcelone-ole\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr\\\/nouvelles\\\/conference-eseb-a-barcelone-ole\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/twitter.com\\\/kafka_project\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCIjYQlwQGZqxnm3GAFkt6_A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr\\\/author\\\/acfabre\\\/#author\",\"url\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr\\\/author\\\/acfabre\\\/\",\"name\":\"Anne-Claire Fabre\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr\\\/nouvelles\\\/conference-eseb-a-barcelone-ole\\\/#webpage\",\"url\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr\\\/nouvelles\\\/conference-eseb-a-barcelone-ole\\\/\",\"name\":\"ESEB conference in Barcelona! Ol\\u00e9! - Meta-Morphosis Project\",\"description\":\"From August 17 to 22, 2025, Morgane Fournier, Vivien Louppe, and I attended the European Society for Evolutionary Biology (ESEB) Congress in Barcelona. I was invited to give a talk as part of a symposium on craniofacial evolution organized by\\u2026\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr\\\/nouvelles\\\/conference-eseb-a-barcelone-ole\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr\\\/author\\\/acfabre\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr\\\/author\\\/acfabre\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/metamorphosis-project.org\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/1000046350.jpg\",\"@id\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr\\\/nouvelles\\\/conference-eseb-a-barcelone-ole\\\/#mainImage\",\"width\":1200,\"height\":1200},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr\\\/nouvelles\\\/conference-eseb-a-barcelone-ole\\\/#mainImage\"},\"datePublished\":\"2025-08-30T15:12:00+00:00\",\"dateModified\":\"2026-07-01T20:12:49+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr\\\/\",\"name\":\"Meta-Morphosis Project\",\"description\":\"How life cycle variation drives biodiversity in changing environments\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/metamorphosis-project.org\\\/fr\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Conf\u00e9rence de l'ESEB \u00e0 Barcelone ! Ol\u00e9 ! - Projet Meta-Morphosis","description":"Du 17 au 22 ao\u00fbt 2025, Morgane Fournier, Vivien Louppe et moi-m\u00eame avons assist\u00e9 au congr\u00e8s de la Soci\u00e9t\u00e9 europ\u00e9enne de biologie \u00e9volutive (ESEB) \u00e0 Barcelone. J\u2019ai \u00e9t\u00e9 invit\u00e9 \u00e0 pr\u00e9senter un expos\u00e9 dans le cadre d\u2019un colloque sur l\u2019\u00e9volution craniofaciale organis\u00e9 par\u2026","canonical_url":"https:\/\/metamorphosis-project.org\/fr\/nouvelles\/conference-eseb-a-barcelone-ole\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/metamorphosis-project.org\/fr\/nouvelles\/conference-eseb-a-barcelone-ole\/#blogposting","name":"ESEB conference in Barcelona! Ol\u00e9! - Meta-Morphosis Project","headline":"ESEB conference in Barcelona! Ol\u00e9!","author":{"@id":"https:\/\/metamorphosis-project.org\/fr\/author\/acfabre\/#author"},"publisher":{"@id":"https:\/\/metamorphosis-project.org\/fr\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/1000046350.jpg","width":1200,"height":1200},"datePublished":"2025-08-30T15:12:00+00:00","dateModified":"2026-07-01T20:12:49+00:00","inLanguage":"fr-FR","mainEntityOfPage":{"@id":"https:\/\/metamorphosis-project.org\/fr\/nouvelles\/conference-eseb-a-barcelone-ole\/#webpage"},"isPartOf":{"@id":"https:\/\/metamorphosis-project.org\/fr\/nouvelles\/conference-eseb-a-barcelone-ole\/#webpage"},"articleSection":"News, Biodiversity, Form-Function, Morphometrics"},{"@type":"BreadcrumbList","@id":"https:\/\/metamorphosis-project.org\/fr\/nouvelles\/conference-eseb-a-barcelone-ole\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/metamorphosis-project.org\/fr#listItem","position":1,"name":"Home","item":"https:\/\/metamorphosis-project.org\/fr","nextItem":{"@type":"ListItem","@id":"https:\/\/metamorphosis-project.org\/fr\/categorie\/nouvelles\/#listItem","name":"News"}},{"@type":"ListItem","@id":"https:\/\/metamorphosis-project.org\/fr\/categorie\/nouvelles\/#listItem","position":2,"name":"News","item":"https:\/\/metamorphosis-project.org\/fr\/categorie\/nouvelles\/","nextItem":{"@type":"ListItem","@id":"https:\/\/metamorphosis-project.org\/fr\/nouvelles\/conference-eseb-a-barcelone-ole\/#listItem","name":"ESEB conference in Barcelona! Ol\u00e9!"},"previousItem":{"@type":"ListItem","@id":"https:\/\/metamorphosis-project.org\/fr#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/metamorphosis-project.org\/fr\/nouvelles\/conference-eseb-a-barcelone-ole\/#listItem","position":3,"name":"ESEB conference in Barcelona! Ol\u00e9!","previousItem":{"@type":"ListItem","@id":"https:\/\/metamorphosis-project.org\/fr\/categorie\/nouvelles\/#listItem","name":"News"}}]},{"@type":"Organization","@id":"https:\/\/metamorphosis-project.org\/fr\/#organization","name":"Meta-Morphosis Project","description":"How life cycle variation drives biodiversity in changing environments","url":"https:\/\/metamorphosis-project.org\/fr\/","logo":{"@type":"ImageObject","url":{"__changed":["mobile"]},"@id":"https:\/\/metamorphosis-project.org\/fr\/nouvelles\/conference-eseb-a-barcelone-ole\/#organizationLogo"},"image":{"@id":"https:\/\/metamorphosis-project.org\/fr\/nouvelles\/conference-eseb-a-barcelone-ole\/#organizationLogo"},"sameAs":["https:\/\/twitter.com\/kafka_project","https:\/\/www.youtube.com\/channel\/UCIjYQlwQGZqxnm3GAFkt6_A"]},{"@type":"Person","@id":"https:\/\/metamorphosis-project.org\/fr\/author\/acfabre\/#author","url":"https:\/\/metamorphosis-project.org\/fr\/author\/acfabre\/","name":"Anne-Claire Fabre"},{"@type":"WebPage","@id":"https:\/\/metamorphosis-project.org\/fr\/nouvelles\/conference-eseb-a-barcelone-ole\/#webpage","url":"https:\/\/metamorphosis-project.org\/fr\/nouvelles\/conference-eseb-a-barcelone-ole\/","name":"ESEB conference in Barcelona! Ol\u00e9! - Meta-Morphosis Project","description":"From August 17 to 22, 2025, Morgane Fournier, Vivien Louppe, and I attended the European Society for Evolutionary Biology (ESEB) Congress in Barcelona. I was invited to give a talk as part of a symposium on craniofacial evolution organized by\u2026","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/metamorphosis-project.org\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/metamorphosis-project.org\/fr\/nouvelles\/conference-eseb-a-barcelone-ole\/#breadcrumblist"},"author":{"@id":"https:\/\/metamorphosis-project.org\/fr\/author\/acfabre\/#author"},"creator":{"@id":"https:\/\/metamorphosis-project.org\/fr\/author\/acfabre\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/1000046350.jpg","@id":"https:\/\/metamorphosis-project.org\/fr\/nouvelles\/conference-eseb-a-barcelone-ole\/#mainImage","width":1200,"height":1200},"primaryImageOfPage":{"@id":"https:\/\/metamorphosis-project.org\/fr\/nouvelles\/conference-eseb-a-barcelone-ole\/#mainImage"},"datePublished":"2025-08-30T15:12:00+00:00","dateModified":"2026-07-01T20:12:49+00:00"},{"@type":"WebSite","@id":"https:\/\/metamorphosis-project.org\/fr\/#website","url":"https:\/\/metamorphosis-project.org\/fr\/","name":"Meta-Morphosis Project","description":"How life cycle variation drives biodiversity in changing environments","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/metamorphosis-project.org\/fr\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"Meta-Morphosis Project - How life cycle variation drives biodiversity in changing environments","og:type":"article","og:title":"ESEB conference in Barcelona! Ol\u00e9! - Meta-Morphosis Project","og:description":"From August 17 to 22, 2025, Morgane Fournier, Vivien Louppe, and I attended the European Society for Evolutionary Biology (ESEB) Congress in Barcelona. I was invited to give a talk as part of a symposium on craniofacial evolution organized by\u2026","og:url":"https:\/\/metamorphosis-project.org\/fr\/nouvelles\/conference-eseb-a-barcelone-ole\/","article:published_time":"2025-08-30T15:12:00+00:00","article:modified_time":"2026-07-01T20:12:49+00:00","twitter:card":"summary_large_image","twitter:site":"@kafka_project","twitter:title":"ESEB conference in Barcelona! Ol\u00e9! - Meta-Morphosis Project","twitter:description":"From August 17 to 22, 2025, Morgane Fournier, Vivien Louppe, and I attended the European Society for Evolutionary Biology (ESEB) Congress in Barcelona. I was invited to give a talk as part of a symposium on craniofacial evolution organized by\u2026","twitter:creator":"@kafka_project"},"aioseo_meta_data":{"post_id":"3660","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"schemas":[],"titles":[],"descriptions":[],"socialPosts":{"email":{"subject":"","preview":"","content":""},"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2026-06-30 14:38:01","updated":"2026-07-01 20:44:26","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/metamorphosis-project.org\/fr\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/metamorphosis-project.org\/fr\/categorie\/nouvelles\/\" title=\"News\">News<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tESEB conference in Barcelona! Ol\u00e9!\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/metamorphosis-project.org\/fr"},{"label":"News","link":"https:\/\/metamorphosis-project.org\/fr\/categorie\/nouvelles\/"},{"label":"ESEB conference in Barcelona! Ol\u00e9!","link":"https:\/\/metamorphosis-project.org\/fr\/nouvelles\/conference-eseb-a-barcelone-ole\/"}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/metamorphosis-project.org\/wp-content\/uploads\/2026\/06\/1000046350.jpg","_links":{"self":[{"href":"https:\/\/metamorphosis-project.org\/fr\/wp-json\/wp\/v2\/posts\/3660","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/metamorphosis-project.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/metamorphosis-project.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/metamorphosis-project.org\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/metamorphosis-project.org\/fr\/wp-json\/wp\/v2\/comments?post=3660"}],"version-history":[{"count":5,"href":"https:\/\/metamorphosis-project.org\/fr\/wp-json\/wp\/v2\/posts\/3660\/revisions"}],"predecessor-version":[{"id":3754,"href":"https:\/\/metamorphosis-project.org\/fr\/wp-json\/wp\/v2\/posts\/3660\/revisions\/3754"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/metamorphosis-project.org\/fr\/wp-json\/wp\/v2\/media\/3683"}],"wp:attachment":[{"href":"https:\/\/metamorphosis-project.org\/fr\/wp-json\/wp\/v2\/media?parent=3660"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/metamorphosis-project.org\/fr\/wp-json\/wp\/v2\/categories?post=3660"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/metamorphosis-project.org\/fr\/wp-json\/wp\/v2\/tags?post=3660"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}